{"id":35523,"date":"2022-02-22T23:57:06","date_gmt":"2022-02-22T23:57:06","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=35523"},"modified":"2022-02-22T23:57:07","modified_gmt":"2022-02-22T23:57:07","slug":"la-comuna-bandena-brindo-asistencia-a-la-escuela-de-futbol-del-barrio-la-fraternidad","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/la-comuna-bandena-brindo-asistencia-a-la-escuela-de-futbol-del-barrio-la-fraternidad\/","title":{"rendered":"LA COMUNA BANDE\u00d1A BRINDO ASISTENCIA A LA ESCUELA DE F\u00daTBOL DEL BARRIO LA FRATERNIDAD"},"content":{"rendered":"\n<p>En este sentido, en representaci\u00f3n de la Secretar\u00eda de Desarrollo Humano, Diego Torres entreg\u00f3 la asistencia al encargado se la escuela de f\u00fatbol, Carlos Gustavo Tapia.<br>En la oportunidad, el responsable de la escuela de f\u00fatbol manifest\u00f3 su agradecimiento por el apoyo recibido y destac\u00f3 la importancia del funcionamiento de la misma ya que son m\u00e1s de cien ni\u00f1os los que concurren semanalmente a los entrenamientos.<br>\u00abEn la mayor\u00eda de los casos los chicos pertenecen a familias de escasos de recursos por lo que se hacia casi imposible cubrir los costos de un viaje as\u00ed fuera de la provincia. Logramos hacerlo y estamos felices de que los ni\u00f1os puedan vivir estas experiencias enriquecedoras que los alientan a seguir practicando un deporte sano\u00bb\u00a0, destac\u00f3 Tapia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del Plan de Asistencia Directa al Vecino, la Municipalidad de La Banda entreg\u00f3 una ayuda econ\u00f3mica a una escuela de f\u00fatbol del barrio La Fraternidad para que alrededor de cien ni\u00f1os puedan participar en un torneo en la provincia de Jujuy.<\/p>\n","protected":false},"author":2,"featured_media":35524,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-35523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"views":15,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/02\/IMG-20220222-WA0023.jpg?fit=1600%2C1200","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=35523"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35523\/revisions"}],"predecessor-version":[{"id":35525,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35523\/revisions\/35525"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/35524"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=35523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=35523"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=35523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}