{"id":35901,"date":"2022-03-01T00:17:29","date_gmt":"2022-03-01T00:17:29","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=35901"},"modified":"2022-03-01T01:15:45","modified_gmt":"2022-03-01T01:15:45","slug":"la-fifa-suspendio-a-rusia-de-todas-las-competencias-y-la-dejo-fuera-del-mundial-de-qatar","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/la-fifa-suspendio-a-rusia-de-todas-las-competencias-y-la-dejo-fuera-del-mundial-de-qatar\/","title":{"rendered":"LA FIFA SUSPENDI\u00d3 A RUSIA DE TODAS LAS COMPETENCIAS Y LA DEJO FUERA DEL MUNDIAL DE QATAR"},"content":{"rendered":"\n<p>El&nbsp;<strong>deporte ruso afronta su ca\u00edda del mapa mundial de las competencias como consecuencia de la invasi\u00f3n militar en Ucrania<\/strong>, decidida la semana pasada por su presidente, Vladimir Putin, que originaron una serie de sanciones en distintos \u00e1mbitos deportivos, entre ellas la exclusi\u00f3n del Mundial Qatar 2022.<\/p>\n\n\n\n<p>La reciente decisi\u00f3n de la FIFA y la UEFA, con la suspensi\u00f3n de todos los equipos rusos en sus competiciones, con apoyo del Comit\u00e9 Ol\u00edmpico Interncional (COI), puso en relieve la magnitud del aislamiento ruso en el deporte.<\/p>\n\n\n\n<p>En este sentido, tanto la UEFA como la FIFA hicieron una excepci\u00f3n porque en el primer d\u00eda del conflicto adelantaron que sus reglamentos no contemplaban la exclusi\u00f3n de una federaci\u00f3n y\/o equipo por razones de \u00abconflicto b\u00e9lico\u00bb.<\/p>\n\n\n\n<p>Desde el jueves 24 de febrero<strong>&nbsp;proliferan las manifestaciones de repudio entre miembros de la comunidad deportiva y las resoluciones contra Rusia no tardaron en aparecer.<\/strong><\/p>\n\n\n\n<p>Un d\u00eda despu\u00e9s del inicio de la guerra,<strong>&nbsp;la UEFA decidi\u00f3 quitarle la final de la Liga de Campeones de Europa<\/strong>, programada para el 28 de mayo en San Petersburgo, y mud\u00f3 la sede a Par\u00eds. El accionar del ente europeo prosigui\u00f3 hoy con la separaci\u00f3n de Spartak Mosc\u00fa de la Liga de Europa, \u00fanico club ruso en competiciones europeas, que deb\u00eda jugar los octavos de final ante Leipzig.<\/p>\n\n\n\n<p>El titular de la FIFA, Gianni Infantino,&nbsp;<strong>se mostr\u00f3 \u00abpreocupado\u00bb por la escalada militar y dio comienzo a un di\u00e1logo con la resolutiva UEFA para suspender al seleccionado ruso de las competiciones internacionales<\/strong>, Qatar 2022 incluido. La Federaci\u00f3n Francesa de F\u00fatbol (FFF), por caso, fue una de las primeras en pronunciarse a favor de la exclusi\u00f3n.<\/p>\n\n\n\n<p>En su primera tanda de sanciones, la FIFA impuso a Rusia jugar bajo el nombre de \u00abFederaci\u00f3n Rusa de F\u00fatbol\u00bb, sin bandera ni himno y con partidos en estadios neutrales, en todas las competencias internacionales previstas. Una medida similar a la impuesta por la Agencia Mundial Antidopaje (AMA) en los Juegos Ol\u00edmpicos de Tokio 2020.<\/p>\n\n\n\n<p>Rusia no jugar\u00e1 la Eurocopa femenina en Inglaterra y tampoco estar\u00e1 en la primera instancia del repechaje a Qatar 2022 del pr\u00f3ximo 24 de marzo ante Polonia, pa\u00eds que rechaz\u00f3 el compromiso desde el inicio de la guerra, a\u00fan en territorio neutral. La respuesta enviada desde Varsovia tuvo r\u00e9plica en otras federaciones como las de Suecia y Rep\u00fablica Checa, posibles rivales en la final.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La selecci\u00f3n del pa\u00eds euroasi\u00e1tica deb\u00eda jugar el 24 de marzo ante Polonia el primer duelo de repechaje mundialista y enfrentar al ganador de Suecia o Rep\u00fablica Checa. La medida tambi\u00e9n afecta al seleccionado femenino -que no disputar\u00e1 la Eurocopa- y al Spartak de Mosc\u00fa, ahora expluido de la Liga de Europa, en la previa de los octavos de final.<\/p>\n","protected":false},"author":2,"featured_media":35902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-35901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"views":7,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/images.jpeg?fit=300%2C168","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=35901"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35901\/revisions"}],"predecessor-version":[{"id":35903,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/35901\/revisions\/35903"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/35902"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=35901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=35901"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=35901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}