{"id":37237,"date":"2022-03-22T12:41:43","date_gmt":"2022-03-22T12:41:43","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37237"},"modified":"2022-03-22T12:41:44","modified_gmt":"2022-03-22T12:41:44","slug":"amplia-convocatoria-en-apoyo-a-pablo-mirolo-y-roger-nediani-en-un-plenario-de-dirigentes-del-frente-renovador","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/amplia-convocatoria-en-apoyo-a-pablo-mirolo-y-roger-nediani-en-un-plenario-de-dirigentes-del-frente-renovador\/","title":{"rendered":"AMPLIA CONVOCATORIA EN APOYO A PABLO MIROLO Y ROGER NEDIANI EN UN PLENARIO DE DIRIGENTES DEL FRENTE RENOVADOR"},"content":{"rendered":"\n<p>Cientos de dirigentes y simpatizantes del Frente Renovador participaron en la tarde noche del martes de un plenario pol\u00edtico demostrando su apoyo al presidente del partido, y reciente vicepresidente de Trenes Argentinos, Pablo Mirolo; y a Roger Nediani quien asume como intendente actual de la ciudad e ir\u00e1 como candidato a Intendente 2022. <\/p>\n\n\n\n<p>En la oportunidad, Mirolo manifest\u00f3: \u00abEstoy muy contento de este momento, en lo personal que estamos viviendo, de este nuevo desaf\u00edo que no est\u00e1 planteado el presidente Alberto Fern\u00e1ndez, de estar al frente de una empresa estatal tan importante y estrat\u00e9gica para la Argentina, un cargo a nivel nacional y que el presidente ha puesto la mirada en nosotros, en un intendente del interior. <\/p>\n\n\n\n<p>Esta es una enorme satisfacci\u00f3n pero a la vez tambi\u00e9n la gran responsabilidad de todo lo que significa, de todo el trabajo que venimos haciendo en la Ciudad de La Banda; que hace 8 a\u00f1os esta gesti\u00f3n se ha animado a marcar un punto de inflexi\u00f3n en la ciudad en materia de obra, de servicio en materia de lo que ha significado tranquilidad para la familia municipal y el progreso y desarrollo que ha tenido todo este tiempo\u00bb.<br>\u00abEra una necesidad de juntarme con ellos, con mis amigos, con mis compa\u00f1eros, con nuestros dirigentes, contarles est\u00e1 buena noticia, el porqu\u00e9 de mi decisi\u00f3n y decirles que esto es un respaldo pol\u00edtico a todo lo que venimos haciendo en La Banda y todo lo que va a venir porque estoy convencido de que el ingeniero Nediani va a ser un gran intendente\u00bb.<br>\u00abVienen momentos muy importantes en la ciudad, con el crecimiento, con obras que se van a llevar adelante, con obras que tenemos que inaugurar y estoy convencido que Roger va a ser lo mejor para la ciudad\u00bb.<br>\u00abHoy es d\u00eda de agradecimiento, agradecerles a todos, a la familia municipal, a cada obrero y obrera, a cada empleado municipal, a cada compa\u00f1ero y cada compa\u00f1era, a cada vecino y cada vecina porque en estos 8 a\u00f1os me han hecho sentir y tener los pies sobre la tierra, de saber que con la humildad, con sacrificio y esfuerzo siempre se llega a todo. <\/p>\n\n\n\n<p>Adem\u00e1s, decirles que tenemos una ciudad hermosa que la hemos logrado consolidar en este tiempo y seguir a\u00fan por m\u00e1s; creo que tenemos que ir por m\u00e1s y ese camino es acompa\u00f1ar a Roger como intendente y en su candidatura para que los pr\u00f3ximos cuatro a\u00f1os sea el intendente de la ciudad\u00bb, concluy\u00f3 Mirolo.<\/p>\n\n\n\n<p>Por su parte, el nuevo candidato a Intendente por el Frente Renovador, Roger Nediani expres\u00f3: \u00abSer candidato para las pr\u00f3ximas elecciones es un gran desaf\u00edo en todos los sentidos porque el trabajo que realiz\u00f3 el intendente en estos casi 8 a\u00f1os es muy importante para nuestra ciudad, hemos remarcado cada una de las obras y el mejoramiento de servicios que se han hecho, eso no lo debemos perder, los bande\u00f1os debemos defender todo lo que venimos haciendo\u00bb.<br>\u00abEsta gesti\u00f3n se ha destacado por el respeto al empleado municipal, pero tambi\u00e9n por el respeto a nuestros hermanos y vecinos de la ciudad de La Banda. La posibilidad de tener contacto directo como vecino o como empleado es superlativo y no s\u00e9 daba en otra \u00e9poca, no es algo com\u00fan y es algo que no debemos perder los bande\u00f1os\u00bb.<br>\u00abQuiero agradecer a todas las compa\u00f1eras y compa\u00f1eros, vecinos y vecinas de la ciudad de La Banda que nos hayan acompa\u00f1ado en este tremendo plenario y decirles que vamos a seguir profundizando todo lo que se viene haciendo en la ciudad de La Banda, decirle que vamos a trabajar m\u00e1s que nunca en mejorar los servicios, que nos acompa\u00f1en porque tenemos muchas obras por hacer. Est\u00e1 gesti\u00f3n es transparente y trabaja en beneficio del vecino, por lo que pido humildemente que nos acompa\u00f1en porque sabemos c\u00f3mo gobernar, conozco cada rinc\u00f3n de nuestra ciudad porque he vivido, fui criado, he jugado, he participado de cu\u00e1nto evento deportivo, cultural y educativo ha habido y por supuesto que lo quiero seguir haciendo; con ese conocimiento de c\u00f3mo funciona la administraci\u00f3n p\u00fablica municipal, quiero pedirles que me ayuden, que me acompa\u00f1en para seguir gobernando la ciudad y no tengan duda que voy a poner absolutamente todo mi esfuerzo, mi capacidad, lo que tengo humildemente en beneficio y a servicio de cada uno de los hermanos bande\u00f1os. Tenemos un rumbo que hemos creado en estos casi 8 a\u00f1os de gesti\u00f3n, la base definitiva para tener un crecimiento y un desarrollo en nuestra ciudad\u00bb, finaliz\u00f3 Nediani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acto se realiz\u00f3 en las instalaciones del Centro Recreativo, ubicado en la esquina de Av. Besares y Alberdi.<\/p>\n","protected":false},"author":2,"featured_media":37238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":["post-37237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"views":7,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/IMG-20220322-WA0000.jpg?fit=1280%2C790","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37237"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37237\/revisions"}],"predecessor-version":[{"id":37239,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37237\/revisions\/37239"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37238"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37237"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}