{"id":37337,"date":"2022-03-23T05:34:23","date_gmt":"2022-03-23T05:34:23","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37337"},"modified":"2022-03-23T05:34:23","modified_gmt":"2022-03-23T05:34:23","slug":"comenzo-el-taller-caminata-saludable-destinado-a-jubilados","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/comenzo-el-taller-caminata-saludable-destinado-a-jubilados\/","title":{"rendered":"COMENZ\u00d3 EL TALLER \u00abCAMINATA SALUDABLE\u00bb DESTINADO A JUBILADOS"},"content":{"rendered":"\n<p>El mismo se da dentro de un plan de trabajo dirigido a adultos mayores y tiene como prop\u00f3sito promover h\u00e1bitos saludables a trav\u00e9s de la realizaci\u00f3n de actividades f\u00edsicas en espacios al aire libre y propiciando un \u00e1mbito para la interacci\u00f3n social.<br>Coordinado por la Subdirecci\u00f3n de la Tercera Edad, el taller es dictado por personal del \u00e1rea de Deportes del municipio y en un espacio que cuenta con las instalaciones adecuadas para que las personas puedan realizar las pr\u00e1cticas deportivas de manera segura. Las actividades se llevan a cabo, los d\u00edas martes y jueves de 8 a 9.30.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizado por la Municipalidad de la Capital, se dio inicio al Taller \u201cCaminata saludable\u201d, destinado a los integrantes de los Centros de Jubilados de la ciudad, en las instalaciones del Parque Sur.<\/p>\n","protected":false},"author":2,"featured_media":37338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-37337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":7,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/jubilados-actividades-muni.jpeg?fit=1600%2C900","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37337"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37337\/revisions"}],"predecessor-version":[{"id":37339,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37337\/revisions\/37339"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37338"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37337"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}