{"id":37559,"date":"2022-03-26T03:59:46","date_gmt":"2022-03-26T03:59:46","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37559"},"modified":"2022-03-26T03:59:46","modified_gmt":"2022-03-26T03:59:46","slug":"argentina-con-messi-como-figura-goleo-a-venezuela-en-la-bombonera","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/argentina-con-messi-como-figura-goleo-a-venezuela-en-la-bombonera\/","title":{"rendered":"ARGENTINA, CON MESSI COMO FIGURA, GOLE\u00d3 A VENEZUELA EN LA BOMBONERA"},"content":{"rendered":"\n<p>El seleccionado argentino, con Lionel Messi como figura, derrot\u00f3 hoy a su par de Venezuela por 3-0, en La Bombonera, y extendi\u00f3 su invicto a 30 partidos, en el marco de la 17ma. y pen\u00faltima fecha de las Eliminatorias Sudamericanas del Mundial Qatar 2022<\/p>\n\n\n\n<p>El capit\u00e1n argentino volvi\u00f3 al seleccionado con una gran actuaci\u00f3n que coron\u00f3 con el gol que marc\u00f3 para el 3-0 definitivo a los 37 minutos del segundo tiempo que desat\u00f3 la fiesta del p\u00fablico en la despedida del equipo del pa\u00eds antes del Mundial.<\/p>\n\n\n\n<p>Nicol\u00e1s Gonz\u00e1lez, a los 34 minutos del primer tiempo, abri\u00f3 el marcador y encamin\u00f3 la victoria \u00abalbiceleste\u00bb y despu\u00e9s el ingresado \u00c1ngel Di Mar\u00eda, a los 33m. de la segunda parte, lo ampli\u00f3 con un golazo con su sello habitual.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"640\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?resize=640%2C640\" alt=\"\" class=\"wp-image-37561 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?resize=1024%2C1024 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?resize=300%2C300 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?resize=150%2C150 150w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?resize=768%2C768 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-1.jpg?w=1080 1080w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/640;\" \/><\/a><\/figure>\n\n\n\n<p>Luego de semanas complicadas por la eliminaci\u00f3n de la Champions League con Par\u00eds Saint Germain, los silbidos de los hinchas y la gripe, el 10 le regal\u00f3 una gran actuaci\u00f3n a los poco m\u00e1s de 50 mil personas que fueron a verlo por \u00faltima vez antes de Qatar.<\/p>\n\n\n\n<p>El capit\u00e1n regres\u00f3 de gran manera, luego de su ausencia en la \u00faltima doble fecha clasificatoria, y mostr\u00f3 todo su repertorio de gambetas, pases y sobre el final con un gol de derecha (con algo de suerte) que gener\u00f3 su risa y la de sus compa\u00f1eros.<\/p>\n\n\n\n<p>Con la victoria, Argentina alcanz\u00f3 los 38 puntos y llev\u00f3 su invicto a los 30 partidos, cada vez m\u00e1s cerca de alcanzar la hist\u00f3rica marca de 33 del ciclo de Alfio Basile, all\u00e1 por la d\u00e9cada del &#8217;90.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"640\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?resize=640%2C640\" alt=\"\" class=\"wp-image-37562 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?resize=1024%2C1024 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?resize=300%2C300 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?resize=150%2C150 150w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?resize=768%2C768 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-2.jpg?w=1080 1080w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/640;\" \/><\/a><\/figure>\n\n\n\n<p>La Venezuela de Jos\u00e9 Pekerman, reconocido en la previa del encuentro, ofreci\u00f3 resistencia hasta la primera hora del partido y deber\u00e1 trabajar mucho para so\u00f1ar con la posibilidad de estar en el Mundial Estados Unidos M\u00e9xico Canad\u00e1 2026.<\/p>\n\n\n\n<p>Con las bajas de Emiliano Mart\u00ednez, Cristian Romero, Marcos Acu\u00f1a, Giovani Lo Celso, \u00c1ngel Di Mar\u00eda y Lautaro Mart\u00ednez, el entrenador Lionel Scaloni tuvo que rearmar el equipo, pero la idea original se mantuvo.<\/p>\n\n\n\n<p>Armani, quien era titular hasta la irrupci\u00f3n de \u00abDibu\u00bb Mart\u00ednez, fue el due\u00f1o del arco, Germ\u00e1n Pezzella acompa\u00f1\u00f3 a Nicol\u00e1s Otamendi en la zaga central.<\/p>\n\n\n\n<p>Las nuevas variantes fueron en la zona media, ya que a Rodrigo De Paul y Leandro Paredes se sum\u00f3 la presencia de Alexis Mac Allister, quien se par\u00f3 como interno por izquierda.<\/p>\n\n\n\n<p>Lionel Messi, la manija del equipo, se ubic\u00f3 libre por el medio y en los extremos estuvieron alternando tanto Nicol\u00e1s Gonz\u00e1lez como Joaqu\u00edn Correa.<\/p>\n\n\n\n\n\n<p>Desde el inicio, la intenci\u00f3n de la Argentina fue tener circulaci\u00f3n de pelota con paciencia para intentar romper la l\u00ednea de cinco defensores planteada por Jos\u00e9 Pekerman. En la primera media hora le cost\u00f3 al equipo poder generar situaciones de peligro. El primer disparo de Messi fue suave a los 3 minutos del primer tiempo.<\/p>\n\n\n\n<p>Despu\u00e9s, reci\u00e9n a los 16m., el equipo encontr\u00f3 otra aproximaci\u00f3n con una recuperaci\u00f3n en campo de propio de Joaqu\u00edn Correa, quien combin\u00f3 con Messi en la entrada al \u00e1rea, pero cuando intent\u00f3 devolv\u00e9rsela se encontr\u00f3 con un defensor venezolano.<\/p>\n\n\n\n<p>El ataque de la \u00abalbiceleste\u00bb iba al ritmo de Messi, porque cuando el astro aceleraba, el p\u00fablico se levantaba. Luego de un par de aproximaciones, el gol finalmente lleg\u00f3 a los 34m., en una jugada que inici\u00f3 -una vez m\u00e1s- Messi que busc\u00f3 sin suerte a Gonz\u00e1lez.<\/p>\n\n\n\n<p>El rechazo de la defensa venezolana fue corto y la presi\u00f3n de Mac Allister tuvo efecto, ya que abri\u00f3 hacia la derecha para De Paul y el ex Racing asisti\u00f3 al medio a Nico Gonz\u00e1lez.<\/p>\n\n\n\n<p>La euforia y el desahogo por el gol gener\u00f3 el primer desencuentro en la defensa de Argentina y la \u00fanica jugada de peligro de Venezuela que tuvo el empate a los 38m., en los pies de Josef Mart\u00ednez, tras centro de Salom\u00f3n Rond\u00f3n desde la derecha.<\/p>\n\n\n\n<p>En el segundo tiempo, el libreto del partido fue similar, ya que Argentina no cedi\u00f3 el protagonismo y fue en busca de m\u00e1s goles para animar a un p\u00fablico que estaba deseoso de gritar goles.<\/p>\n\n\n\n<p>La llave del ataque estaba en la zurda de Messi, que a los 18m. lo dej\u00f3 solo a Correa, que en vez de definir de zurda quiso enganchar. Despu\u00e9s, el jugador del Inter fue reemplazado por \u00c1ngel Correa y complet\u00f3 una noche dif\u00edcil por la tarea de reemplazar a Lautaro Mart\u00ednez.<\/p>\n\n\n\n<p>Cuando el partido parec\u00eda quedar en el 1-0 solitario, el ingreso de \u00c1ngel Di Mar\u00eda, uno de los m\u00e1s requeridos por el p\u00fablico, cambi\u00f3 la historia y reaviv\u00f3 el clima de fiesta para homenajear a los campeones de Am\u00e9rica.<\/p>\n\n\n\n<p>Unos minutos despu\u00e9s de entrar, \u00abFideo\u00bb recibi\u00f3 un gran pase de De Paul, otro de los puntos altos del equipo, y ante la salida de Far\u00ed\u00f1ez defini\u00f3 de emboquillada, su marca registrada en los goles con la Selecci\u00f3n.<\/p>\n\n\n\n<p>Pero para coronar la noche faltaba algo y era el gol de Messi. El crack del PSG cumpli\u00f3 porque Di Mar\u00eda arm\u00f3 una buena jugada por derecha y lo dej\u00f3 solo en el \u00e1rea chica.<\/p>\n\n\n\n<p>El ganador de siete Balones de Oro domin\u00f3 y defini\u00f3 con la derecha mordida pero le alcanz\u00f3 para superar a Fari\u00f1ez y desatar la fiesta en La Bombonera.<\/p>\n\n\n\n<p>Un nuevo paso para la \u00abScaloneta\u00bb, que pese a los cambios afianza su idea, extiende la racha invicta y sue\u00f1a de la mano del pibe de casi 35 a\u00f1os.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">S\u00edntesis del partido<\/h3>\n\n\n\n<p><strong>Argentina:<\/strong>&nbsp;Franco Armani; Nahuel Molina, Germ\u00e1n Pezzella, Nicol\u00e1s Otamendi y Nicol\u00e1s Tagliafico; Rodrigo De Paul, Leandro Paredes y Alexis Mac Allister; Lionel Messi, Joaqu\u00edn Correa y Nicol\u00e1s Gonz\u00e1lez. DT: Lionel Scaloni.<\/p>\n\n\n\n<p><strong>Venezuela:<\/strong>&nbsp;Wuilker Fari\u00f1ez; Roberto Rosales, Nahuel Ferraresi, Jhon Chancellor, Christian Makoun y Miguel Navarro; Jos\u00e9 Mart\u00ednez, Cristian Casseres y Yangel Herrera; Josef Mart\u00ednez y Salom\u00f3n Rond\u00f3n. DT: Jos\u00e9 Pekerman.<\/p>\n\n\n\n<p><strong>Gol en el primer tiempo:<\/strong>&nbsp;34m. Nicol\u00e1s Gonz\u00e1lez (A)<\/p>\n\n\n\n<p><strong>Goles en el segundo tiempo:<\/strong>&nbsp;33m. Di Mar\u00eda&nbsp;; 37m. Messi<\/p>\n\n\n\n<p><strong>Cambios:&nbsp;<\/strong>en el segundo tiempo, antes del inicio, Jhon Murillo por Navarro (V); 16m. Fernando Aristeguieta por Josef Mart\u00ednez y Luis Gonz\u00e1lez por C\u00e1sseres (V); 18m. \u00c1ngel Correa por Joaqu\u00edn Correa&nbsp;; 24m. \u00c1ngel Di Mar\u00eda por Mac Allister&nbsp;; 31m. Darwin Mach\u00eds por Herrera (V)<\/p>\n\n\n\n<p><strong>Amonestados:<\/strong>&nbsp;Navarro, Chancellor, Herrera, Rosales (V)<\/p>\n\n\n\n<p><strong>\u00c1rbitro:&nbsp;<\/strong>Kevin Ortega (Per\u00fa)<\/p>\n\n\n\n<p><strong>Estadio:<\/strong>&nbsp;La Bombonera<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00abAlbiceleste\u00bb super\u00f3 por 3 a 0 Venezuela, en un partido correspondiente a la 17ma. y pen\u00faltima fecha de las Eliminatorias Sudamericanas jugado en la Bombonera. Nicol\u00e1s Gonz\u00e1lez convirti\u00f3 en el primer tiempo, mientras que \u00c1ngel Di Mar\u00eda y Lionel Messi marcaron en el segundo.<\/p>\n","protected":false},"author":2,"featured_media":37560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-37559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"aioseo_notices":[],"views":6,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/ARGENTINA-PORTADA.jpg?fit=2540%2C1693","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37559"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37559\/revisions"}],"predecessor-version":[{"id":37564,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37559\/revisions\/37564"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37560"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37559"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}