{"id":37573,"date":"2022-03-26T23:22:48","date_gmt":"2022-03-26T23:22:48","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37573"},"modified":"2022-03-26T23:22:49","modified_gmt":"2022-03-26T23:22:49","slug":"el-intendente-nediani-visito-el-centro-de-comercio","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/el-intendente-nediani-visito-el-centro-de-comercio\/","title":{"rendered":"EL INTENDENTE NEDIANI VISIT\u00d3 EL CENTRO DE COMERCIO"},"content":{"rendered":"\n<p>Durante la misma, el jefe comunal tom\u00f3 conocimiento acerca de las necesidades del sector comercial como as\u00ed tambi\u00e9n de las inquietudes que atraviesa el mismo.<br>En la entrevista, la presidente del Centro, Stella Maris Gallegos manifest\u00f3: \u201cPara m\u00ed es un honor y un gusto poder recibir al flamante intendente y s\u00e9 que har\u00e1 una excelente gesti\u00f3n porque conoce La Banda integra y tiene mucha experiencia desde joven as\u00ed que no dudo de que va a tener una buena gesti\u00f3n\u201d.<br>Asimismo, manifest\u00f3 que tiene la confianza de que el intendente Nediani les dar\u00e1 la respuesta a lo que realmente necesita la sociedad y el comercio bande\u00f1o.<br>Por su parte, el flamante intendente interioriz\u00f3 y escuch\u00f3 sugerencias para continuar trabajando de manera mancomunada, buscando siempre los mejores beneficios tanto para los comerciantes bande\u00f1os como para los vecinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente, Roger Nediani mantuvo en la tarde del viernes una reuni\u00f3n en el Centro de Comercio e Industria de la ciudad de La Banda.<\/p>\n","protected":false},"author":2,"featured_media":37574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-37573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":10,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/IMG-20220325-WA0015.jpg?fit=1280%2C853","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37573"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37573\/revisions"}],"predecessor-version":[{"id":37575,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37573\/revisions\/37575"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37574"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37573"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}