{"id":37607,"date":"2022-03-27T23:21:09","date_gmt":"2022-03-27T23:21:09","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37607"},"modified":"2022-03-27T23:27:22","modified_gmt":"2022-03-27T23:27:22","slug":"a-los-82-anos-murio-enrique-pinti","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/a-los-82-anos-murio-enrique-pinti\/","title":{"rendered":"A LOS 82 A\u00d1OS, MURI\u00d3 ENRIQUE PINTI"},"content":{"rendered":"\n<p>El actor y dramaturgo Enrique Pinti falleci\u00f3 hoy a los 82 a\u00f1os dejando una extensa trayectoria de m\u00e1s de seis d\u00e9cadas en el mundo de la comedia y la actuaci\u00f3n donde de la mano de sucesos como&nbsp;<strong>\u00abSalsa criolla\u00bb, con el que se mantuvo 10 a\u00f1os ininterrumpidos en cartel<\/strong>, consolid\u00f3 un protagonismo de relevancia en la historia del espect\u00e1culo nacional.<\/p>\n\n\n\n<p>Nacido el 7 de octubre de 1939 en Buenos Aires, el artista fue internado de urgencia y gravedad el 5 de marzo en el Sanatorio Otamendi, aquejado por un cuadro de diabetes severa y problemas circulatorios en las piernas, y aunque desde entonces experiment\u00f3 mejor\u00edas, no logr\u00f3 reponerse de manera definitiva y muri\u00f3 esta madrugada.<\/p>\n\n\n\n<p><strong>Due\u00f1o de un estilo personal y vers\u00e1til<\/strong>\u00a0dominado por un humor punzante que desplegaba a inusitada velocidad verbal, Pinti transcurri\u00f3 con \u00e9xito el \u00e1mbito de la televisi\u00f3n, la radio, el teatro, el cine, la literatura -ya que escribi\u00f3 13 libros desde 1990- y hasta la m\u00fasica al grabar \u00abRadio Pinti\u00bb (1991) junto a Charly Garc\u00eda (quien lo consideraba el mayor rapero de Argentina) y Pedro Aznar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/3OKIGB5PMJFU3F3ZTDLGDB2NRY.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/3OKIGB5PMJFU3F3ZTDLGDB2NRY.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-37610 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/3OKIGB5PMJFU3F3ZTDLGDB2NRY.jpg?w=1023 1023w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/3OKIGB5PMJFU3F3ZTDLGDB2NRY.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/3OKIGB5PMJFU3F3ZTDLGDB2NRY.jpg?resize=768%2C512 768w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/a><\/figure>\n\n\n\n<p>En teatro, se dedic\u00f3 tanto a obras infantiles como para adultos desde la escritura, direcci\u00f3n e interpretaci\u00f3n y sus mon\u00f3logos humor\u00edsticos de caf\u00e9-concert, en muchos casos reflexivos sobre la actualidad pol\u00edtica, lo convirtieron en uno de los pioneros de la escena local de lo que despu\u00e9s se rotular\u00eda como stand-up comedy en el pa\u00eds.<\/p>\n\n\n\n<p><strong>A partir de su estilo \u00e1cido y malhablado, el humorista supo construir \u00e9xitos teatrales<\/strong>&nbsp;como \u00abHistorias recogidas\u00bb I y II (1973 a 1975 y 1978 a 1979), \u00abEl show de Enrique Pinti\u00bb (1980), \u00abVote Pinti\u00bb (1983), \u00abSalsa criolla\u00bb (que desde 1985 fue un r\u00e9cord en el teatro de habla hispana, con 3000 representaciones, dos millones de espectadores y prestigiosos premios en su haber), \u00abPinti y aparte\u00bb (1992), \u00abEl infierno de Pinti\u00bb (1997), \u00abPericon.com.ar\u00bb (2000), \u00abCandombe nacional\u00bb (2002 a 2004) y \u00abAntes de que me olvide\u00bb (2010).<\/p>\n\n\n\n<p>Pinti&nbsp;<strong>tuvo una colaboraci\u00f3n muy exitosa con su colega Antonio Gasalla&nbsp;<\/strong>entre 1973 y 1986, per\u00edodo en el que coescribi\u00f3 todos los espect\u00e1culos de su amigo y produjo nueve obras con las que obtuvieron r\u00e9cord teatrales durante varias temporadas en el Maipo y el Teatro Liceo.<\/p>\n\n\n\n<p>Adem\u00e1s, el dramaturgo&nbsp;<strong>trabaj\u00f3 en varias adaptaciones de obras extranjeras<\/strong>&nbsp;como \u00abChicago\u00bb para N\u00e9lida Lobato, \u00abFilomena Marturano\u00bb, \u00abYo quiero a mi mujer\u00bb y \u00abLos locos Addams\u00bb.<\/p>\n\n\n\n<p>Tambi\u00e9n realiz\u00f3 la adaptaci\u00f3n de las canciones de El joven Frankenstein, obra que protagoniz\u00f3 Guillermo Francella, y trabaj\u00f3 en la adaptaci\u00f3n y como actor en comedias musicales como \u00abHairspray\u00bb, \u00abLos productores\u00bb y \u00abAnything Goes\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/enrique-pinti-revelo-que-le-ofrecieron-tener-prioridad-para-vacunarse-y-el-dijo-que-no-1130848.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"480\" height=\"480\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/enrique-pinti-revelo-que-le-ofrecieron-tener-prioridad-para-vacunarse-y-el-dijo-que-no-1130848.jpg?resize=480%2C480\" alt=\"\" class=\"wp-image-37612 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/enrique-pinti-revelo-que-le-ofrecieron-tener-prioridad-para-vacunarse-y-el-dijo-que-no-1130848.jpg?w=480 480w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/enrique-pinti-revelo-que-le-ofrecieron-tener-prioridad-para-vacunarse-y-el-dijo-que-no-1130848.jpg?resize=300%2C300 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/enrique-pinti-revelo-que-le-ofrecieron-tener-prioridad-para-vacunarse-y-el-dijo-que-no-1130848.jpg?resize=150%2C150 150w\" data-sizes=\"(max-width: 480px) 100vw, 480px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 480px; --smush-placeholder-aspect-ratio: 480\/480;\" \/><\/a><\/figure>\n\n\n\n<p>De los&nbsp;<strong>19 a los 30 a\u00f1os, Pinti se form\u00f3 y trabaj\u00f3 en el Nuevo Teatro<\/strong>, compa\u00f1\u00eda independiente creada en 1949 por Alejandra Boero y Pedro Asquini, donde actu\u00f3 en obras teatrales y escribi\u00f3 y dirigi\u00f3 comedias musicales infantiles.<\/p>\n\n\n\n<p>Luego de actuar en la pel\u00edcula \u00abEl secuestrador\u00bb (1958), dirigida por Leopoldo Torre Nilsson y protagonizada por Leonardo Favio, en 1969 comenz\u00f3 a hacer guiones para programas como \u00abLa Botica del \u00c1ngel\u00bb, conducido por Eduardo Bergara Leumann, \u00abCasino\u00bb y \u00abLa luna de Canela\u00bb, adem\u00e1s de escribir una versi\u00f3n de \u00abDon Segundo Sombra\u00bb.<\/p>\n\n\n\n<p>Pinti tambi\u00e9n particip\u00f3 en gr\u00e1fica en los setenta escribiendo la historieta de \u00abEl mono relojero\u00bb, dibujada por Daniel Branca y publicada por la revista Billiken.<\/p>\n\n\n\n<p>Ya desde 1973 se dedic\u00f3 con m\u00e1s especializaci\u00f3n a los espect\u00e1culos unipersonales e incursion\u00f3 en el g\u00e9nero del caf\u00e9 concert con su show \u00abHistorias recogidas\u00bb en el Teatro Latino de San Telmo, que se mantuvo hasta 1975.<\/p>\n\n\n\n<p><strong>En 1976, debut\u00f3 en El Maipo<\/strong>&nbsp;de gala bajo la direcci\u00f3n de Gerardo Sofovich, junto a Osvaldo Pacheco, Carmen Barbieri, Thelma Stefani, Trist\u00e1n, Alberto Ir\u00edzar, y un a\u00f1o despu\u00e9s actu\u00f3 en \u00abEl humor de Nin\u00ed Marshall\u00bb.<\/p>\n\n\n\n<p>Bajo la direcci\u00f3n de Antonio Gasalla, estren\u00f3 en 1982 \u00abPan y circo\u00bb, en la que Pinti interpretaba personajes hist\u00f3ricos como Ner\u00f3n o la Reina Isabel, obra por la que fue invitado al Festival Latinoamericano de Teatro de Nueva York y fue premiado por ese espect\u00e1culo.<\/p>\n\n\n\n<p>\u00abSalsa Criolla\u00bb, quiz\u00e1 su obra m\u00e1s reconocida, premiada y taquillera, se estren\u00f3 en 1984 en el Teatro Liceo y repasaba en un formato de musical de \u00e9poca la historia argentina desde el descubrimiento de Am\u00e9rica hasta la actualidad.<\/p>\n\n\n\n<p>En cine, el actor tuvo roles secundarios en \u00abSentimental\u00bb (1981) y en la recordada \u00abEsperando la carroza\u00bb (1985) de Alejandro Doria, en la que interpret\u00f3 a un alcoh\u00f3lico llamado Felipe.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/E1eb2DpWQAIaAkU.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/E1eb2DpWQAIaAkU.jpg?resize=405%2C304\" alt=\"\" class=\"wp-image-37614 lazyload\" width=\"405\" height=\"304\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/E1eb2DpWQAIaAkU.jpg?w=640 640w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/E1eb2DpWQAIaAkU.jpg?resize=300%2C225 300w\" data-sizes=\"(max-width: 405px) 100vw, 405px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 405px; --smush-placeholder-aspect-ratio: 405\/304;\" \/><\/a><figcaption>Ok<\/figcaption><\/figure>\n\n\n\n<p>En la d\u00e9cada del 90 tambi\u00e9n estuvo con V\u00edctor Laplace y Federico Luppi en \u00abFlop\u00bb (1990) y junto a Ricardo Dar\u00edn en \u00abPerdido por perdido\u00bb (1993), rol que le vali\u00f3 premios de los festivales de Cartagena y La Habana y un C\u00f3ndor de Plata.<\/p>\n\n\n\n<p><strong>En 1992 estren\u00f3 su propio ciclo televisivo: \u00abPinti y los ping\u00fcinos\u00bb<\/strong>, con producci\u00f3n de Carlos Rottemberg y Daniel Tinayre, y en 1997 realiz\u00f3 giras presentando sus mejores mon\u00f3logos.<\/p>\n\n\n\n<p>Entre sus participaciones como columnista invitado, Pinti colabor\u00f3 en Clar\u00edn, La Naci\u00f3n y Noticias y en el \u00e1mbito de la radio estuvo en Mitre en \u00abHoy por hoy\u00bb con N\u00e9stor Ibarra y en Continental en \u00abMagdalena tempran\u00edsimo\u00bb, colaboraciones que le dieron dos Mart\u00edn Fierro en 2003 y 2007.<\/p>\n\n\n\n<p>A su vez, Pinti\u00a0<strong>recibi\u00f3 dos Mart\u00edn Fierro m\u00e1s en 2009 y 2012<\/strong>\u00a0al mejor programa cultural educativo, cuando se dedic\u00f3 a hacer programas sobre pel\u00edculas: \u00abPinti y el cine\u00bb por la TV P\u00fablica y \u00abLuz, c\u00e1mara, Pinti\u00bb por Todo Noticias.<\/p>\n\n\n\n<p>En cuanto a galardones, el experimentado artista adem\u00e1s recibi\u00f3 en 1991 el Premio Konex de platino por su unipersonal y como mejor actor de musical en 2001 y en 2006 obtuvo el Estrella de Mar de Oro al protag\u00f3nico de comedia.<\/p>\n\n\n\n<p><strong>En 2015, al cumplirse treinta a\u00f1os de su presentaci\u00f3n, se reestren\u00f3 en el Teatro Liceo \u00abSalsa criolla\u00bb<\/strong>&nbsp;y tuvo una gira nacional que cerr\u00f3 con presentaciones en Montevideo, Uruguay.<\/p>\n\n\n\n<p>Con 79 a\u00f1os, \u00abAl fondo a la derecha\u00bb debut\u00f3 en 2019 y fue el \u00faltimo show del humorista, un espect\u00e1culo unipersonal mezclado con n\u00fameros musicales de otros shows de su autor\u00eda que debi\u00f3 suspender por una crisis de salud.<\/p>\n\n\n\n<p><strong>Durante la pandemia y la cuarentena, Pinti present\u00f3 en agosto un show desde su casa v\u00eda streaming con el periodista Marcelo Polino: \u00abPinti y Polino al hueso\u00bb<\/strong>, que tuvo dos funciones y buena cantidad de p\u00fablico conectada a trav\u00e9s de internet.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor falleci\u00f3 esta madrugada en el Sanatorio Otamendi, donde se encontraba internado en estado delicado desde principios de marzo por una descompensaci\u00f3n causada por la diabetes severa y problemas circulatorios en las piernas.<\/p>\n","protected":false},"author":2,"featured_media":37608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[20],"tags":[],"class_list":["post-37607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-especysociales"],"aioseo_notices":[],"views":11,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/6JBKYRS6UFGRXHPL73FX55FD5U.jpg?fit=1023%2C682","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37607"}],"version-history":[{"count":3,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37607\/revisions"}],"predecessor-version":[{"id":37616,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37607\/revisions\/37616"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37608"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37607"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}