{"id":37672,"date":"2022-03-28T20:10:05","date_gmt":"2022-03-28T20:10:05","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=37672"},"modified":"2022-03-28T20:10:05","modified_gmt":"2022-03-28T20:10:05","slug":"el-intendente-nediani-visito-las-instalaciones-del-camm-del-rincon","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/el-intendente-nediani-visito-las-instalaciones-del-camm-del-rincon\/","title":{"rendered":"EL INTENDENTE NEDIANI VISIT\u00d3 LAS INSTALACIONES DEL CAMM DEL RINC\u00d3N"},"content":{"rendered":"\n<p>En la oportunidad, el intendente hizo referencia a la importancia de mencionada instalaci\u00f3n, la cual cubre un importante sector de la ciudad, y agreg\u00f3: \u00abMuy contento de poder conversar con cada uno de los empleados de esta instituci\u00f3n, insentivando a continuar con el trabajo en beneficio de los vecinos de la ciudad y proponiendo que contin\u00faen dando el m\u00e1ximo de los esfuezos, como lo vienen haciendo hasta el momento con el mayor de los compromisos\u00bb.<br>\u00abEste es el mensaje para todas las \u00e1reas, de las cuales tengo las intenciones de visitar cada una, teniendo esta cercan\u00eda para interiorzarme de como se desempe\u00f1an, como se sienten. La idea es que cada uno de ellos pueda ir mejorando personalmente en todos los aspectos laborales, con mi acompa\u00f1amiento, trabajando siempre en el beneficio de la ciudad\u00bb finaliz\u00f3 el mandatario.<br>Cabe destacar, que los servicios que brinda dicha instituci\u00f3n por la ma\u00f1ana son: cirujano, los d\u00edas martes a las 10:30 horas; odontolog\u00eda, los mi\u00e9rcoles y jueves a las 8; m\u00e9dico cl\u00ednico, los jueves y viernes a las 8:30. Por la tarde: obstetra, lunes martes y jueves a las 16, viernes a las 14; cirujano, a las 13; ecograf\u00edas, lunes a las 16.<br>El servicio de vacunaci\u00f3n se brinda de lunes a viernes, en el horario de 8 a 12; el servicio de enfermer\u00eda de lunes a viernes, en el horario de 8 a 18; servicio de farmacia, de lunes a viernes, en el horario de 8 a 12 por la ma\u00f1ana y por la tarde los lunes jueves y viernes, en los horarios de 14 a 18.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de la ciudad de La Banda, Roger Nediani, junto a dem\u00e1s autoridades, visit\u00f3 las instalaciones del CAMM N\u00b06 del barrio El Rinc\u00f3n y dialog\u00f3 con todo el equipo de trabajo para conocer la actualidad del sistema de atenci\u00f3n y dem\u00e1s.<\/p>\n","protected":false},"author":2,"featured_media":37673,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-37672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":8,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/03\/IMG-20220328-WA0007.jpg?fit=1160%2C868","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=37672"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37672\/revisions"}],"predecessor-version":[{"id":37674,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/37672\/revisions\/37674"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/37673"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=37672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=37672"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=37672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}