{"id":38514,"date":"2022-04-13T00:44:12","date_gmt":"2022-04-13T00:44:12","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=38514"},"modified":"2022-04-13T00:44:13","modified_gmt":"2022-04-13T00:44:13","slug":"se-reportaron-2-077-nuevos-casos-de-coronavirus-en-argentina","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/se-reportaron-2-077-nuevos-casos-de-coronavirus-en-argentina\/","title":{"rendered":"SE REPORTARON 2.077 NUEVOS CASOS DE CORONAVIRUS EN ARGENTINA"},"content":{"rendered":"\n<p>Otras 35 personas murieron y 2.077 fueron reportadas con coronavirus en las \u00faltimas 24 horas en la Argentina, con lo que suman 128.268 los fallecidos registrados oficialmente a nivel nacional y 9.056.203 los contagiados desde el inicio de la pandemia, inform\u00f3 el Ministerio de Salud.<\/p>\n\n\n\n<p>La cartera sanitaria indic\u00f3 que son&nbsp;<strong>424 los internados con coronavirus en unidades de terapia intensiva,&nbsp;<\/strong>con un porcentaje de ocupaci\u00f3n de camas de adultos en el sector p\u00fablico y privado, para todas las patolog\u00edas, de 37,3% en el pa\u00eds y de 39% en el \u00c1rea Metropolitana de Buenos Aires.<\/p>\n\n\n\n<p><strong>De acuerdo con el Monitor P\u00fablico de Vacunaci\u00f3n, el total de dosis aplicadas es de 97.432.845,<\/strong>&nbsp;de los cuales 40.664.771 corresponden a primeras dosis, 37.096.121 a ambas, 3.027.427 a una adicional y 16.644.526 a refuerzo, mientras que las vacunas distribuidas a las jurisdicciones llegan a 105.004.184 y las donadas a 5.083.000.<\/p>\n\n\n\n<p>De los 9.056.203 contagiados, 8.888.514 recibieron el alta y 39.421 son casos confirmados activos.<\/p>\n\n\n\n<p>El parte precis\u00f3 que murieron 11 hombres, 7 en la provincia de Buenos Aires, 1 en la Ciudad Aut\u00f3noma de Buenos Aires, 1 en C\u00f3rdoba, 1 en Jujuy y 1 en Santa Fe.<\/p>\n\n\n\n<p>Tambi\u00e9n fallecieron 24 mujeres: 13 en la provincia de Buenos Aires, 5 en la Ciudad Aut\u00f3noma de Buenos Aires, 1 en Chaco, 1 en R\u00edo Negro y 4 en Santa Fe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Contagios por distrito<\/h3>\n\n\n\n<p>Este martes se reportaron en la provincia de Buenos Aires 721 casos; en la Ciudad de Buenos Aires, 530; en Catamarca, 27; en Chaco, 9; en Chubut, 61; en Corrientes, 48; en C\u00f3rdoba, 155; en Entre R\u00edos, 39; en Formosa, 4; en Jujuy, 3; en La Pampa, 34; en Mendoza, 30; en Misiones, 252; en Neuqu\u00e9n, 14; en R\u00edo Negro, 35; en Salta, 2; en San Juan, 9; en San Luis, 7; en Santa Cruz, 46; en Santa Fe, 31; en Santiago del Estero, 3; en Tierra del Fuego, 1 y en Tucum\u00e1n, 27.<\/p>\n\n\n\n<p>Por su parte, La Rioja no registr\u00f3 ning\u00fan caso en las \u00faltimas 24 horas.<\/p>\n\n\n\n<p>El Ministerio indic\u00f3 adem\u00e1s que se realizaron en las \u00faltimas 24 horas 25.286 testeos y desde el inicio del brote ascienden a 35.657.472 las pruebas diagn\u00f3sticas para esta enfermedad.<\/p>\n\n\n\n<p>El total de acumulados por distrito indica para la provincia de Buenos Aires 3.548.575 casos; la Ciudad de Buenos Aires, 1.020.760; Catamarca, 86.966; Chaco, 167.669; Chubut, 118.307; Corrientes, 132.675; C\u00f3rdoba, 968.591; Entre R\u00edos, 201.175; Formosa, 113.968; Jujuy, 105.442; La Pampa, 106.599; La Rioja, 56.905; Mendoza, 272.316; Misiones, 67.882; Neuqu\u00e9n, 168.683; R\u00edo Negro, 147.160; Salta, 155.376; San Juan, 145.670; San Luis, 134.586; Santa Cruz, 88.053; Santa Fe, 739.505; Santiago del Estero, 124.879; Tierra del Fuego, 46.854; y Tucum\u00e1n, 337.607.<\/p>\n\n\n\n<p>Se incluyen casos existentes en las Islas Malvinas seg\u00fan informaci\u00f3n de prensa (debido a la ocupaci\u00f3n ilegal del Reino Unido, Gran Breta\u00f1a e Irlanda del Norte no es posible contar con informaci\u00f3n propia sobre el impacto de la Covid-19 en esa parte del territorio argentino).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con estas cifras suman 9.056.203 los contagiados y 128.268 los fallecidos registrados oficialmente a nivel nacional y desde el inicio de la pandemia, inform\u00f3 el Ministerio de Salud. <\/p>\n","protected":false},"author":2,"featured_media":38516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-38514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"aioseo_notices":[],"views":6,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/W3PNA2AIUVCLTOCBZ6ZNSTGKLA.jpg?fit=580%2C330","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/38514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=38514"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/38514\/revisions"}],"predecessor-version":[{"id":38517,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/38514\/revisions\/38517"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/38516"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=38514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=38514"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=38514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}