{"id":39406,"date":"2022-04-30T00:56:53","date_gmt":"2022-04-30T00:56:53","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=39406"},"modified":"2022-04-30T00:56:53","modified_gmt":"2022-04-30T00:56:53","slug":"cierre-de-la-semana-de-vacunacion-de-las-americas-2022","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/cierre-de-la-semana-de-vacunacion-de-las-americas-2022\/","title":{"rendered":"CIERRE DE LA SEMANA DE VACUNACI\u00d3N DE LAS AM\u00c9RICAS 2022"},"content":{"rendered":"\n<p>Bajo el lema \u00ab20 A\u00f1os, 20 vacunas\u00bb con la presencia del subsecretario de Salud, Cesar Monti; la jefa del Programa Provincial de Inmunizaciones, Florencia Coronel, quien dijo: \u00abSe est\u00e1n celebrando 20 a\u00f1os de la Semana de Vacunaci\u00f3n de las Am\u00e9ricas y se adecua al lema que rige este a\u00f1o, ya que tenemos 20 vacunas gratuitas en el calendario nacional, lo que es un hecho muy importante\u00bb. Adem\u00e1s agreg\u00f3: \u00abEsta semana queremos hacer visible y poner al d\u00eda todo el calendario, no solo contra la Covid-19, sino todas las dem\u00e1s vacunas para ni\u00f1os, adultos, embarazadas y todas las edades y demostrar que la salud no solo esta en los hospitales, sino tambi\u00e9n en los espacios p\u00fablicos abiertos\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-39408 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?resize=1536%2C1024 1536w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?w=1600 1600w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0035.jpg?w=1280 1280w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/a><\/figure>\n\n\n\n<p>En la celebraci\u00f3n se instalaron stands de distintos programas de salud de la provincia, como la Direcci\u00f3n de APS a trav\u00e9s de las plazas saludables, sonrisas santiague\u00f1as; vacunaci\u00f3n contra el Covid-19 y de calendario regular de vacunaci\u00f3n para la gripe a mayores de 65 a\u00f1os y grupos de riesgo. Tambi\u00e9n se realizaron testeos gratuitos por HIV en el stand del Programa VIH\/ SIDA, ITS Y Hepatitis virales; Y al celebrarse el \u00abD\u00eda del Animal\u00bb se promocion\u00f3 el cuidado de los animales y la vacunaci\u00f3n antirr\u00e1bica.<\/p>\n\n\n\n<p>Para finalizar se dio clase de baile y la realizaci\u00f3n de sorteos de bicicletas, tablets, como una forma de reconocimiento a la comunidad en su compromiso con la campa\u00f1a de vacunaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la explanada del Centro de Convenciones F\u00d3RUM, sobre calle Roca, se realiz\u00f3 el cierre de la Semana de Vacunaci\u00f3n de Las Am\u00e9ricas 2022.<\/p>\n","protected":false},"author":2,"featured_media":39407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-39406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud"],"aioseo_notices":[],"views":10,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/04\/IMG-20220429-WA0034.jpg?fit=1600%2C1067","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=39406"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39406\/revisions"}],"predecessor-version":[{"id":39409,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39406\/revisions\/39409"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/39407"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=39406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=39406"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=39406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}