{"id":39493,"date":"2022-05-02T02:23:43","date_gmt":"2022-05-02T02:23:43","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=39493"},"modified":"2022-05-02T02:25:14","modified_gmt":"2022-05-02T02:25:14","slug":"los-precios-de-los-aceites-de-girasol-y-soja-tuvieron-un-incremento-superior-al-20-por-la-guerra-de-ucrania","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/los-precios-de-los-aceites-de-girasol-y-soja-tuvieron-un-incremento-superior-al-20-por-la-guerra-de-ucrania\/","title":{"rendered":"LOS PRECIOS DE LOS ACEITES DE GIRASOL Y SOJA TUVIERON UN INCREMENTO SUPERIOR AL 20%"},"content":{"rendered":"\n<p>Los precios internacionales de los aceites vegetales, en especial de girasol y soja, fueron dos de los productos agr\u00edcolas industrializados que subieron con fuerza tras desatarse la guerra entre Rusia y Ucrania, con incrementos superiores al 20%.<\/p>\n\n\n\n<p>Seg\u00fan la&nbsp;<strong>Bolsa de Comercio de Rosario (BCR)<\/strong>, desde el inicio del conflicto b\u00e9lico, el 24 de febrero,&nbsp;<strong>los precios del aceite de soja en el mercado de Chicago aumentaron casi un 25%<\/strong>&nbsp;al pasar de US$ 1.587,30 a US$ 1.965 al cierre del viernes pasado, mientras el precio FOB de exportaci\u00f3n del aceite de girasol argentino subi\u00f3 21%, de US$ 1.660 a US$ 2.015 en similar per\u00edodo.<\/p>\n\n\n\n<p>La raz\u00f3n que dispar\u00f3 la suba de estos productos fue la invasi\u00f3n rusa a Ucrania, que adem\u00e1s del desastre humanitario y econ\u00f3mico que gener\u00f3, tambi\u00e9n paraliz\u00f3 la industria aceitera y el movimiento de los puertos sobre el Mar Negro, lo que retir\u00f3 del mercado a la producci\u00f3n de aceite de girasol proveniente de esa zona, que en conjunto representan el 80% del volumen comercializado a nivel mundial.<\/p>\n\n\n\n<p>Esto no solo dispar\u00f3 el precio del aceite de girasol, sino tambi\u00e9n de aquellos que son sustitutos, como el de soja, palma o de ma\u00edz.<\/p>\n\n\n\n<p><strong>\u00abEl mayor efecto de la guerra fue en el aceite de girasol, porque desapareci\u00f3 el 80% (de la oferta mundial) y en ese instante, el precio vol\u00f3 de US$ 1500 a US$ 2.200\u00bb<\/strong>, se\u00f1al\u00f3 a T\u00e9lam el presidente de la C\u00e1mara de la Industria Aceitera y del Centro de Exportadores de Cereales (Ciara-CEC), Gustavo Id\u00edgoras.<\/p>\n\n\n\n<p>Esta suba en los precios repercute no solo en las exportaciones del complejo girasolero, sino tambi\u00e9n en el aporte que realiza a la econom\u00eda argentina.<\/p>\n\n\n\n<p>Seg\u00fan un informe de la Bolsa de Cereales de Buenos Aires (BCBA),&nbsp;<strong>el Producto Bruto Agr\u00edcola (PBA) del complejo alcanzar\u00eda en la presente campa\u00f1a 2021\/22 el monto r\u00e9cord de US$ 1.909 millones<\/strong>, US$ 217 millones por encima de lo registrado en el ciclo pasado, con una expansi\u00f3n del 12,8%.<\/p>\n\n\n\n<p>En cuanto a las exportaciones, la entidad proyect\u00f3 ingresos por US$ 1.202 millones, lo que representar\u00e1 un aumento del 18,2% (US$ 185 millones), mientras que la recaudaci\u00f3n por retenciones tendr\u00e1 un incremento de US$ 69 millones hasta los US$ 426 millones.<\/p>\n\n\n\n<p>Asimismo, la entidad calcul\u00f3 que de las 3,4 millones de toneladas recientemente cosechadas, 3 millones se moler\u00e1n para la producci\u00f3n de aceite mayoritariamente, por lo que 750.000 toneladas quedar\u00edan disponibles para la exportaci\u00f3n, unas 50.000 toneladas menos que en la campa\u00f1a 2020\/21.<\/p>\n\n\n\n<p>Ese volumen, indic\u00f3 Id\u00edgoras, representa el 8% del mercado mundial, \u00aby fue el \u00fanico aceite de girasol que qued\u00f3 disponible tras la desaparici\u00f3n de la oferta ucraniana y, lamentablemente, no se pudo atender y qued\u00f3 insatisfecha la demanda mundial\u00bb.<\/p>\n\n\n\n<p>Ante esta situaci\u00f3n, el dirigente empresario ve \u00abuna enorme oportunidad para la cadena girasolera argentina, con buenos precios y un mercado insatisfecho\u00bb, lo que podr\u00eda determinar un crecimiento en el \u00e1rea implantada con dicho cultivo, cuya superficie en la \u00faltima campa\u00f1a fue de 1,7 millones de hect\u00e1reas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/ACEITES-1.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/ACEITES-1.jpg?resize=640%2C384\" alt=\"\" class=\"wp-image-39495 lazyload\" width=\"640\" height=\"384\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/384;\" \/><\/a><\/figure>\n\n\n\n<p>Por el lado del&nbsp;<strong>aceite de soja, la suba de los precios internacionales, en torno al 25%<\/strong>, tambi\u00e9n tendr\u00e1 su impacto positivo en las exportaciones argentina.<\/p>\n\n\n\n<p>El \u00faltimo informe de Panorama de Mercados de la BCR, los despachos de este producto escalar\u00edan hasta los US$ 7.733 millones este a\u00f1o, US$ 632 millones m\u00e1s que el a\u00f1o pasado y US$ 330 millones por encima de lo que se esperaba en las estimaciones del mes pasado de la entidad burs\u00e1til.<\/p>\n\n\n\n<p>No obstante, el equipo econ\u00f3mico de la BCR remarc\u00f3 que \u00abla pol\u00edtica de retenciones actual podr\u00eda desalentar la industrializaci\u00f3n y el comercio exterior de productos del complejo sojero\u00bb lo cual \u00abpodr\u00eda limitar la captura de este nivel de precios\u00bb.<\/p>\n\n\n\n<p>La entidad burs\u00e1til explic\u00f3 que la demanda de aceite de soja en el \u00faltimo tiempo \u00abse vio apuntalada en parte para sustituir la escasez de aceite de girasol\u00bb, cuesti\u00f3n que no solo impuls\u00f3 los precios de este subproducto en cuesti\u00f3n, sino a lo de todo el complejo de soja.<\/p>\n\n\n\n<p>A esto se sum\u00f3 que en los \u00faltimos d\u00edas,&nbsp;<strong>Indonesia anunci\u00f3 la suspensi\u00f3n de exportaciones del aceite de palma<\/strong>, otro producto sustituto.<\/p>\n\n\n\n<p>Este pa\u00eds del sudeste asi\u00e1tico es responsable de m\u00e1s de la mitad de las exportaciones globales de este aceite e iba camino este a\u00f1o a representar el 56% de las exportaciones mundiales de aceite de palma, se\u00f1al\u00f3 la BCR, por lo que \u00aba la incertidumbre de abastecimiento global se le suma la incertidumbre regulatoria en este pa\u00eds\u00bb.<\/p>\n\n\n\n<p>\u00abEste es otro factor que apuntala a los precios, en vista de potencial incremento de la demanda de aceite de soja para sustituir palma, como se vio con el girasol\u00bb, finaliz\u00f3 el an\u00e1lisis de la Bolsa rosarina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de la cat\u00e1strofe humanitaria, la invasi\u00f3n gener\u00f3 un enorme efecto en el aceite de girasol, porque desapareci\u00f3 el 80% de la oferta mundial. Dirigentes empresariales ven \u00abuna enorme oportunidad para la cadena girasolera argentina, con buenos precios y un mercado insatisfecho\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":39494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,2],"tags":[],"class_list":["post-39493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-economia"],"aioseo_notices":[],"views":9,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/ACEITES.jpeg?fit=800%2C450","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=39493"}],"version-history":[{"count":2,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39493\/revisions"}],"predecessor-version":[{"id":39497,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39493\/revisions\/39497"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/39494"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=39493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=39493"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=39493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}