{"id":39750,"date":"2022-05-09T18:12:51","date_gmt":"2022-05-09T18:12:51","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=39750"},"modified":"2022-05-09T18:12:51","modified_gmt":"2022-05-09T18:12:51","slug":"fernandez-voy-a-trabajar-incansablemente-para-que-el-bolsillo-de-los-argentinos-sea-cada-dia-mas-fuerte","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/fernandez-voy-a-trabajar-incansablemente-para-que-el-bolsillo-de-los-argentinos-sea-cada-dia-mas-fuerte\/","title":{"rendered":"FERN\u00c1NDEZ: \u00abVOY A TRABAJAR INCANSABLEMENTE PARA QUE EL BOLSILLO DE LOS ARGENTINOS SEA CADA D\u00cdA M\u00c1S FUERTE\u00bb"},"content":{"rendered":"\n<p>\u201cAs\u00ed como me ocup\u00e9, me ocupo y me voy a seguir ocupando de que el trabajo crezca en al Argentina, voy a trabajar incansablemente para que el bolsillo de los argentinos sea cada d\u00eda m\u00e1s fuerte, para que cada vez haya m\u00e1s dinero en el bolsillo de los que trabajan\u201d, dijo el mandatario junto al secretario general de la CGT, Hector Daer; el titular de FATSA, Carlos West Ocampo, y las secretarias generales de las filiales de Oliva, Luc\u00eda Farf\u00e1n, y de San Cruz, Silvia Leiva.<\/p>\n\n\n\n<p>Fern\u00e1ndez asegur\u00f3 que \u201ctenemos la oportunidad de hacer una Argentina mejor, tenemos el deber moral de construir una sociedad m\u00e1s justa porque somos sobrevivientes de una pandemia. Dios nos dio la oportunidad de seguir viviendo. Que eso nos obligue a construir un mejor pa\u00eds, un pa\u00eds m\u00e1s unido y una sociedad m\u00e1s justa\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"426\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?resize=640%2C426\" alt=\"\" class=\"wp-image-39752 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?resize=1024%2C682 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?resize=1536%2C1024 1536w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?w=1940 1940w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad.jpg?w=1280 1280w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/426;\" \/><\/a><\/figure>\n\n\n\n<p>Ante dirigentes, delegados, delegadas y congresales representantes de todas las filiales del pa\u00eds del sector de la sanidad, el jefe de Estado afirm\u00f3 que durante la pandemia de Covid-19 \u201cno hubo ning\u00fan argentino que se quedara sin la atenci\u00f3n m\u00e9dica que necesitaba\u201d, y explic\u00f3 que eso fue posible \u201cporque estaban ustedes, los trabajadores de la salud, hombres y mujeres, enfermeros, enfermeras, medicos, medicas, todos poniendo su esfuerzo, todos siendo la primera l\u00ednea para parar al virus\u201d.<\/p>\n\n\n\n<p>\u201cGracias por el esfuerzo que han hecho, gracias por el esfuerzo que hacen y por el esfuerzo que har\u00e1n\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p>El mandatario, quien asisti\u00f3 acompa\u00f1ado por el secretario general de la Presidencia, Julio Vitobello, dijo que el Gobierno nacional est\u00e1 trabajando en \u201chacer m\u00e1s fuerte la atenci\u00f3n en la salud de la Argentina\u201d y asegur\u00f3 que \u201ceso incluye tambi\u00e9n mejorar paulatinamente el ingreso de los que prestan salud en el pa\u00eds, de los trabajadores y las trabajadoras, reconocer un enfermero, reconocer una enfermera, el rol que cumplen en esta sociedad\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"426\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?resize=640%2C426\" alt=\"\" class=\"wp-image-39753 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?resize=1024%2C682 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?resize=300%2C200 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?resize=768%2C512 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?resize=1536%2C1024 1536w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?w=1940 1940w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad3.jpg?w=1280 1280w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/426;\" \/><\/a><\/figure>\n\n\n\n<p>El secretario General de la CGT y el Sindicato de Trabajadores de la Sanidad Argentina, H\u00e9ctor Daer, agradeci\u00f3 al Presidente por su presencia en la actividad, y afirm\u00f3: \u201cAtravesamos a\u00f1os muy dif\u00edciles para nuestra labor profesional, pero estamos trabajando firmemente en construir una salud universal y para todos\u201d.<\/p>\n\n\n\n<p>\u201cLa defensa de la seguridad social en la atenci\u00f3n frente al primer ataque del coronavirus resulta muy importante. Tenemos muestra cabal de eso en que ning\u00fan argentino qued\u00f3 sin atenci\u00f3n durante todo este tiempo de pandemia\u201d, expres\u00f3 Daer.<\/p>\n\n\n\n<p>Por su parte, el secretario General de la Federaci\u00f3n de Asociaciones de Trabajadores de la Sanidad Argentina (FATSA), Carlos West Ocampo, precis\u00f3 que \u201ceste Congreso tan particular es el primero que hacemos\u201d de manera presencial \u201cdespu\u00e9s de la pandemia\u201d, y defini\u00f3: \u201cHemos honrado hoy no solo a los muertos de nuestra organizaci\u00f3n por la pandemia, que fueron much\u00edsimos, sino tambi\u00e9n a todos los h\u00e9roes y hero\u00ednas\u201d de otros \u00e1mbitos que perdieron la vida durante ese tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Alberto Fern\u00e1ndez dijo que el Gobierno va \u201ca trabajar incansablemente para que el bolsillo de los argentinos sea cada d\u00eda m\u00e1s fuerte\u201d, al participar este mediod\u00eda en el 57\u00b0 Congreso Ordinario de Federaci\u00f3n de Asociaciones Trabajadores de la Sanidad Argentina (FATSA) que se realiz\u00f3 en el predio de Parque Norte de la Ciudad de Buenos Aires.<\/p>\n","protected":false},"author":2,"featured_media":39751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":["post-39750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"views":9,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/05\/AFSanidad2.jpg?fit=1940%2C1293","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=39750"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39750\/revisions"}],"predecessor-version":[{"id":39754,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/39750\/revisions\/39754"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/39751"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=39750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=39750"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=39750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}