{"id":43547,"date":"2022-08-11T13:58:08","date_gmt":"2022-08-11T13:58:08","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=43547"},"modified":"2022-08-11T13:58:09","modified_gmt":"2022-08-11T13:58:09","slug":"raverta-el-objetivo-es-que-ningun-jubilado-pierda-capacidad-de-compra-y-pierda-contra-la-inflacion","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/raverta-el-objetivo-es-que-ningun-jubilado-pierda-capacidad-de-compra-y-pierda-contra-la-inflacion\/","title":{"rendered":"RAVERTA: \u00abEL OBJETIVO ES QUE NING\u00daN JUBILADO PIERDA CAPACIDAD DE COMPRA Y PIERDA CONTRA LA INFLACI\u00d3N\u00bb"},"content":{"rendered":"\n<p>La titular de la Administraci\u00f3n Nacional de la Seguridad Social (Anses), Fernanda&nbsp;<strong>Raverta, afirm\u00f3 que el objetivo del organismo previsional es que \u00abning\u00fan jubilado pierda capacidad de compra y pierda contra la inflaci\u00f3n\u00bb<\/strong>&nbsp;y que, en ese sentido, con el \u00faltimo aumento de movilidad y el refuerzo mensual \u00ablas jubilaciones m\u00ednimas aumentaron por arriba de la inflaci\u00f3n casi ocho puntos, un 7,9%\u00bb.<\/p>\n\n\n\n<p>\u00abLo que estamos haciendo es poniendo en marcha una estrategia que nos permita garantizar lo que nos propusimos cuando asumimos el conducir el organismo que es que ning\u00fan jubilado pierda capacidad de compra y pierda contra la inflaci\u00f3n\u00bb, asever\u00f3 Raverta esta ma\u00f1ana en di\u00e1logo con la radio AM 750.<\/p>\n\n\n\n<p>Con el incremento de 15,53% previsto por la f\u00f3rmula de movilidad, anunciado el mi\u00e9rcoles por Raverta junto con el ministro de Econom\u00eda, Sergio Massa, la jubilaci\u00f3n m\u00ednima pasar\u00e1 de $ 37.525 a $ 50.353 a partir de septiembre, mientras que las dos jubilaciones m\u00ednimas aumentar\u00e1n de $ 75.050 a $ 90.705.<\/p>\n\n\n\n<p><strong>A este aumento, que alcanza a 16 millones de jubilados, se le sumar\u00e1 un refuerzo mensual de hasta $ 7.000 pesos<\/strong>&nbsp;que se pagar\u00e1 en septiembre, octubre y noviembre hasta el pr\u00f3ximo incremento por movilidad previsto para diciembre.<\/p>\n\n\n\n<p>Dicho refuerzo alcanza a 6,1 millones de personas, casi el 85% de todas las jubilaciones, e ir\u00e1 decreciendo de forma progresiva hasta los $ 4.000, monto que cobrar\u00e1n quienes tengan ingresos de hasta dos haberes m\u00ednimos.<\/p>\n\n\n\n<p>En un hilo en su cuenta de Twitter, Massa detall\u00f3 el mi\u00e9rcoles que el refuerzo ser\u00e1 financiado \u201cmanteniendo el orden en las cuentas por el incremento que representa el adelanto del Impuesto a las Ganancias\u201d.<\/p>\n\n\n\n<p><strong>\u201cCon este aumento trimestral podemos decir que las jubilaciones m\u00ednimas aumentaron por arriba de la inflaci\u00f3n en casi 8 puntos, un 7,9%\u201d<\/strong>, destac\u00f3 la directora de la Anses.<\/p>\n\n\n\n<p>Tras lo cual, agreg\u00f3: \u201cDe esta manera, estamos siempre con una propuesta para que los jubilados y jubiladas puedan estar tranquilos de que ese compromiso que asumimos de la capacidad de compra en sus haberes no lo dejamos de cumplir\u00bb.<\/p>\n\n\n\n<p>Asimismo, subray\u00f3 que, con este aumento, \u00abning\u00fan jubilado en la Argentina tiene ingresos por menos de $ 50.000 y eso es importante para nosotros\u00bb.<\/p>\n\n\n\n<p><strong>\u00abAc\u00e1 es importante decir que cuando sabemos que tenemos un problema, en este caso la inflaci\u00f3n, siempre tiene que haber una respuesta que resuelva ese problema<\/strong>&nbsp;porque los gobiernos tenemos esa responsabilidad\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p>Por otro lado, cuestion\u00f3 a \u00ablas notas\u00bb que citan a la canasta b\u00e1sica para medir los ingresos jubilatorios, porque \u00abla jubilaci\u00f3n es un ingreso individual y la canasta se calcula por familia\u00bb.<\/p>\n\n\n\n<p>Por \u00faltimo, Raverta reiter\u00f3 que el sistema previsional aporta al \u201ccirculo virtuoso de la econom\u00eda\u00bb.<\/p>\n\n\n\n<p><strong>\u00abCuando ponemos dinero en los jubilados o en los chicos y chicas de la asignaci\u00f3n familiar, estamos poniendo dinero que va al consumo<\/strong>&nbsp;y el consumo, como sabemos, mueve a la econom\u00eda y a que las cosas anden mejor\u00bb, concluy\u00f3 la funcionaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jubilaci\u00f3n m\u00ednima pasar\u00e1 de $ 37.525 a $ 50.353 a partir de septiembre, mientras que las dos jubilaciones m\u00ednimas aumentar\u00e1n de $ 75.050 a $ 90.705.<\/p>\n","protected":false},"author":2,"featured_media":43548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-43547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"aioseo_notices":[],"views":7,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/RAVERTA.jpg?fit=1004%2C565","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/43547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=43547"}],"version-history":[{"count":1,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/43547\/revisions"}],"predecessor-version":[{"id":43549,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/43547\/revisions\/43549"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/43548"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=43547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=43547"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=43547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}