{"id":44138,"date":"2022-08-26T02:58:04","date_gmt":"2022-08-26T02:58:04","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=44138"},"modified":"2022-08-26T02:59:46","modified_gmt":"2022-08-26T02:59:46","slug":"villa-ojo-de-agua-celebro-su-138-aniversario-con-inauguracion-de-obras-y-entrega-de-viviendas","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/villa-ojo-de-agua-celebro-su-138-aniversario-con-inauguracion-de-obras-y-entrega-de-viviendas\/","title":{"rendered":"VILLA OJO DE AGUA CELEBR\u00d3 SU 138\u00b0 ANIVERSARIO CON OBRAS Y VIVIENDAS"},"content":{"rendered":"\n<p>Las unidades habitacionales fueron construidas por el municipio con fondos provinciales y se encuentran distribuidas en los parajes La Maza, San Miguel, Las Jarillas, Tala Cruz, La Pampa, El Abra y en los barrios Municipal, El Tala Viejo y Panor\u00e1mico.<\/p>\n\n\n\n<p>De la ceremonia participaron los ministros de Desarrollo Social, \u00c1ngel Niccolai y de Producci\u00f3n, Miguel Mandrille; la presidenta del Consejo de Educaci\u00f3n, Mar\u00eda Elena Herrera, y jefes comunales de la zona, entre otras autoridades que fueron recibidas por el intendente Antonio Bittar y la electa jefa comunal, M\u00f3nica Bustamante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?resize=640%2C427\" alt=\"\" class=\"wp-image-44139 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?resize=1024%2C683 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?resize=300%2C200 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?resize=768%2C512 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?resize=1536%2C1024 1536w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?w=1599 1599w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.18-PM.jpeg?w=1280 1280w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/a><\/figure>\n\n\n\n<p>En la oportunidad, se ley\u00f3 el saludo del gobernador Gerardo Zamora a todos los vecinos de Villa Ojo de Agua, a quienes inst\u00f3 a continuar trabajando de manera mancomunada por el crecimiento de la ciudad.<br>Adem\u00e1s, miembros del Concejo Deliberante entregaron las ordenanzas mediante las cuales se impusieron los nombres de \u00abWalter Chiquit\u00edn Maldonado\u00bb a la Casa de la Cultura y de \u00abLisando Orlando Leiva\u00bb a un Paseo del barrio La Merced, en reconocimiento a figuras destacadas de la cultura de esta ciudad.<\/p>\n\n\n\n<p>Al hacer uso de la palabra Bittar dijo: \u00abSiempre hemos pensando en pol\u00edticas p\u00fablicas para mejorar la calidad de vida de la gente, como las viviendas sociales y en este sentido hemos trabajado fuerte con el Gobierno de la provincia para ejecutar obras fundamentales en esta ciudad. Adem\u00e1s de contribuir al desarrollo productivo de la provincia con el matadero frigor\u00edfico cabritero\u00bb.<br>En el final, destac\u00f3 el nuevo edificio del colegio secundario local que se encuentra en construcci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"484\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg?resize=640%2C484\" alt=\"\" class=\"wp-image-44141 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg?resize=1024%2C774 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg?resize=300%2C227 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg?resize=768%2C581 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.20-PM-1.jpeg?w=1280 1280w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/484;\" \/><\/a><\/figure>\n\n\n\n<p>A su turno, Niccolai dijo que los aniversarios de los pueblos y ciudades son para celebrar y realizar balances de las acciones logradas y agreg\u00f3: \u00abLas obras habilitadas son evidencia del crecimiento de esta ciudad y esto es parte del trabajo iniciado en el 2005 para construir una provincia para todos, con inclusi\u00f3n e igualdad de oportunidades\u00bb.<br>Por \u00faltimo, asegur\u00f3: \u00abOjo de Agua es un lugar tur\u00edstico, atractivo, con mucho potencial para la provincia y el pa\u00eds. Seguiremos acompa\u00f1ando desde el Estado provincial para que esta ciudad siga siendo el faro de crecimiento de esta zona\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunidad de Villa Ojo de Agua vivi\u00f3 una jornada memorable con motivo de su 138\u00b0 aniversario, con la entrega de 9 viviendas sociales y 7 m\u00f3dulos habitacionales. Tambi\u00e9n fueron inauguradas las obras de saneamiento de canal revestido, pavimento, cord\u00f3n cuneta, alumbrado p\u00fablico y el edificio del Jard\u00edn de Infantes del paraje Amoladeras.<\/p>\n","protected":false},"author":2,"featured_media":44140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-44138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":9,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-25-at-11.41.19-PM.jpeg?fit=1280%2C788","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/44138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=44138"}],"version-history":[{"count":2,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/44138\/revisions"}],"predecessor-version":[{"id":44144,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/44138\/revisions\/44144"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/44140"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=44138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=44138"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=44138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}