{"id":45914,"date":"2022-10-24T21:41:04","date_gmt":"2022-10-24T21:41:04","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=45914"},"modified":"2022-10-24T23:04:13","modified_gmt":"2022-10-24T23:04:13","slug":"alberto-fernandez-encabezo-la-inauguracion-de-los-juegos-evita-2022","status":"publish","type":"post","link":"http:\/\/elterritorialweb.com.ar\/web\/alberto-fernandez-encabezo-la-inauguracion-de-los-juegos-evita-2022\/","title":{"rendered":"ALBERTO FERN\u00c1NDEZ ENCABEZ\u00d3 LA INAUGURACI\u00d3N DE LOS JUEGOS EVITA 2022"},"content":{"rendered":"\n<p>El presidente Alberto Fern\u00e1ndez asegur\u00f3 este lunes que<strong>&nbsp;\u00abes bueno saber que cualquier rinc\u00f3n de la patria tiene representaci\u00f3n en estos juegos\u00bb<\/strong>, al encabezar en Mar del Plata la inauguraci\u00f3n de las Finales Nacionales de los Juegos Evita 2022, que se desarrollar\u00e1n hasta el pr\u00f3ximo s\u00e1bado con la participaci\u00f3n de m\u00e1s de 25.000 competidores.<\/p>\n\n\n\n<p><strong>\u00abEl deporte es una maravillosa escuela y una gran ense\u00f1anza\u00bb,<\/strong>&nbsp;agreg\u00f3 el mandatario.<\/p>\n\n\n\n<p>Del acto de apertura participaron tambi\u00e9n el ministro de Deportes y Turismo, Mat\u00edas Lammens, y de Cultura, Trist\u00e1n Bauer.<\/p>\n\n\n\n<p>La ciudad \u00abFeliz\u00bb acoger\u00e1 las finales de los Juegos Evita tanto en su tradicional rama deportiva y tambi\u00e9n el cierre de la 17ma. edici\u00f3n de los Juegos Culturales Evita, bajo el lema \u00abConstruyendo diversidad cultural\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"315\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png?resize=640%2C315\" alt=\"\" class=\"wp-image-45917 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png?resize=1024%2C504 1024w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png?resize=300%2C148 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png?resize=768%2C378 768w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-2001582.png?w=1320 1320w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/315;\" \/><\/a><\/figure>\n\n\n\n<p>La fase final deportiva reunir\u00e1 a 25 mil competidores repartidos en 63 disciplinas, mientras la cultural contar\u00e1 con dos mil finalistas de todas las provincias que participaron en las categor\u00edas sub 15, sub 18, categor\u00eda \u00fanica (de 12 a 18 a\u00f1os) y, por primera vez, a personas con discapacidad.<\/p>\n\n\n\n<p>La edici\u00f3n 2022 de las finales nacionales de los Juegos Evita cuenta con doce nuevas competencias:&nbsp;<strong>siete convencionales (Escalada, Futsal, Handball de Playa, Pat\u00edn Carrera, Tenis, Tiro con arco y Skate) y otras cinco adaptadas para personas con discapacidad (b\u00e1dminton, f\u00fatbol 3, powerlifting, taekwondo y tenis).<\/strong><\/p>\n\n\n\n<p>La provincia de Buenos Aires present\u00f3 la delegaci\u00f3n m\u00e1s grande de su historia ya que es integrada por m\u00e1s de 1.000 personas entre deportistas, entrenadores, coordinadores, m\u00e9dicos y autoridades provinciales, seg\u00fan informaron fuentes oficiales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciudad \u00abFeliz\u00bb acoger\u00e1 las finales de los Juegos Evita tanto en su tradicional rama deportiva y tambi\u00e9n el cierre de la 17ma. edici\u00f3n de los Juegos Culturales Evita, bajo el lema \u00abConstruyendo diversidad cultural\u00bb.<\/p>\n","protected":false},"author":2,"featured_media":45915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"class_list":["post-45914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"aioseo_notices":[],"views":26,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2022\/10\/Screenshot_20221024-1838412.png?fit=1270%2C695","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/45914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=45914"}],"version-history":[{"count":2,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/45914\/revisions"}],"predecessor-version":[{"id":45918,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/45914\/revisions\/45918"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/45915"}],"wp:attachment":[{"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=45914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=45914"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=45914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}