{"id":227,"date":"2020-02-19T21:31:36","date_gmt":"2020-02-19T21:31:36","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=227"},"modified":"2020-02-19T22:04:25","modified_gmt":"2020-02-19T22:04:25","slug":"bolsonaro-recibira-a-felipe-sola-en-el-palacio-presidencial","status":"publish","type":"post","link":"https:\/\/elterritorialweb.com.ar\/web\/bolsonaro-recibira-a-felipe-sola-en-el-palacio-presidencial\/","title":{"rendered":"Bolsonaro recibir\u00e1 a Felipe Sol\u00e1 en el palacio presidencial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente brasile\u00f1o confirm\u00f3 que recibir\u00e1 el mi\u00e9rcoles al canciller, en un encuentro privado en el palacio presidencial del Planalto que tiene como meta principal superar las rispideces entre ambos gobiernos. De no mediar inconvenientes, quedar\u00e1 m\u00e1s cerca la bilateral entre el derechista y Fern\u00e1ndez.<br>\nLa reuni\u00f3n entre Sol\u00e1 y el mandatario, prevista para las tres de la tarde, fue incluida esta noche en la agenda oficial del presidente y confirmada por su vocero a LA NACION. Ser\u00e1 el plato fuerte de la visita de Sol\u00e1 a Brasil, que tiene como uno de los principales objetivos dejar atr\u00e1s los cortocircuitos entre los gobiernos argentino y brasile\u00f1o. Adem\u00e1s, el funcionario argentino se encontrar\u00e1 con su par en Brasil, Ernesto Ara\u00fajo, en una agenda oficial que comenzar\u00e1 a las 11.<br>\nLa versi\u00f3n de un encuentro cara a cara entre Bolsonaro y Sol\u00e1 hab\u00eda comenzado a cobrar fuerza la ma\u00f1ana del martes, luego de que el brasile\u00f1o confirmara a periodistas que lo recibir\u00eda en caso de que hubiera oportunidad. De todos modos, no se esperan grandes acuerdos bilaterales tras el viaje argentino, seg\u00fan supo LA NACION, debido a la falta de trabajo conjunto de los equipos t\u00e9cnicos de ambas canciller\u00edas en la previa.<br>\nLa principal meta de las reuniones, seg\u00fan reconocen en ambas orillas, ser\u00e1 archivar los desencuentros entre Bolsonaro y Alberto Fern\u00e1ndez. Estas desavenencias se remontan incluso a cuando el peronista todav\u00eda era candidato y el presidente brasile\u00f1o no ocult\u00f3 su deseo de que Mauricio Macri se impusiera en la elecci\u00f3n, para \u00abevitar una nueva Venezuela\u00bb en Am\u00e9rica del Sur.<br>\nD\u00edas atr\u00e1s, Bolsonaro, quien se ausent\u00f3 de la jura de Fern\u00e1ndez en diciembre, carg\u00f3 contra el gobierno argentino, al que calific\u00f3 de \u00absocialista\u00bb por la implementaci\u00f3n de la doble indemnizaci\u00f3n contra despidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A poco de aterrizar en Brasil, la misi\u00f3n argentina encabezada por Felipe Sol\u00e1 recibi\u00f3 un primer gui\u00f1o de Jair Bolsonaro.<\/p>\n","protected":false},"author":2,"featured_media":228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[18],"tags":[],"class_list":["post-227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"aioseo_notices":[],"views":8,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/84499464_125416202327786_8039593752026677248_o.jpg?fit=525%2C350&ssl=1","_links":{"self":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=227"}],"version-history":[{"count":1,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/227\/revisions"}],"predecessor-version":[{"id":229,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/227\/revisions\/229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/228"}],"wp:attachment":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}