{"id":676,"date":"2020-02-25T15:28:39","date_gmt":"2020-02-25T15:28:39","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=676"},"modified":"2020-02-25T15:28:42","modified_gmt":"2020-02-25T15:28:42","slug":"alberto-fernandez-pidio-disculpas-por-sus-dichos","status":"publish","type":"post","link":"https:\/\/elterritorialweb.com.ar\/web\/alberto-fernandez-pidio-disculpas-por-sus-dichos\/","title":{"rendered":"ALBERTO FERNANDEZ PIDI\u00d3 DISCULPAS POR SUS DICHOS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La semana pasada, Alberto Fern\u00e1ndez llam\u00f3 a \u201cdar vuelta la p\u00e1gina\u201d en la relaci\u00f3n con las Fuerzas Armadas. Fue el viernes 21 de febrero, cuando encabez\u00f3 junto al ministro de Defensa, Agust\u00edn Rossi, la ceremonia de despedida de un nuevo contingente de Cascos Azules en Campo de Mayo.<br>\u00abEs un d\u00eda especial porque procedemos a la renovaci\u00f3n de quienes han estado al mando de nuestras Fuerzas Armadas, que hoy est\u00e1n totalmente integradas a la sociedad argentina. Quiero darles la bienvenida a los nuevos jefes y manifestar mi alegr\u00eda por el hecho de que hoy todos los oficiales y suboficiales son hombres de la democracia, egresaron de sus escuelas en democracia y esto amerita que de una vez por todas demos vuelta la p\u00e1gina y celebremos\u201d, sostuvo el jefe de Estado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"360\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/ALBERTO-FERNANDEZ-DISCULPAS.png?resize=640%2C360\" alt=\"\" class=\"wp-image-678 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/ALBERTO-FERNANDEZ-DISCULPAS.png?w=750&amp;ssl=1 750w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/ALBERTO-FERNANDEZ-DISCULPAS.png?resize=300%2C169&amp;ssl=1 300w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/360;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Luego de escuchar el discurso de Alberto Fern\u00e1ndez, Nora Corti\u00f1as repudi\u00f3 sus dichos y sostuvo que \u201cno hay posibilidad de reconciliaci\u00f3n con los genocidas\u201d. \u201cRechazo totalmente todas las expresiones del Presidente. No ten\u00eda ninguna necesidad de expresarse as\u00ed. Pienso que es un negacionista. No podemos aceptar dar vuelta la hoja ni cerrar la exigencia de que se abran los archivos y que nos digan qu\u00e9 pas\u00f3 con todos y cada uno de los detenidos\/desaparecidos\u201d, asegur\u00f3 la referente de Madres de Plaza de Mayo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de las cr\u00edticas de Nora Corti\u00f1as, el Presidente se disculp\u00f3 desde su cuenta de Twitter. \u201cQue un error m\u00edo no nos divida. No quiero pasar por distra\u00eddo ante la queja justa\u201d<\/p>\n","protected":false},"author":2,"featured_media":677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[7,18],"tags":[],"class_list":["post-676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales","category-politica"],"aioseo_notices":[],"views":7,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/ALBERTO-FERNANDEZ-DISCULPAS-1.png?fit=320%2C158&ssl=1","_links":{"self":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":1,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/676\/revisions"}],"predecessor-version":[{"id":679,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/676\/revisions\/679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/677"}],"wp:attachment":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}