{"id":700,"date":"2020-02-25T17:43:44","date_gmt":"2020-02-25T17:43:44","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=700"},"modified":"2020-02-25T17:43:46","modified_gmt":"2020-02-25T17:43:46","slug":"intensos-trabajos-en-el-armado-del-festival-del-artesano","status":"publish","type":"post","link":"https:\/\/elterritorialweb.com.ar\/web\/intensos-trabajos-en-el-armado-del-festival-del-artesano\/","title":{"rendered":"INTENSOS TRABAJOS EN EL ARMADO DEL FESTIVAL DEL ARTESANO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">OJO DE AGUA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La 25\u00b0 Edici\u00f3n del Festival Nacional del Artesano en Villa Ojo de Agua promete ser un verdadero \u00e9xito. Cientos de personas de toda la zona llegar\u00e1n a la ciudad el 27, 28 y 29 de este mes para disfrutar de esta celebraci\u00f3n que se convirti\u00f3 en una de las m\u00e1s importantes de la regi\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO2.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-702 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO2.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO2.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO2.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Desde la organizaci\u00f3n se est\u00e1 realizando intensos trabajos en el armado del escenario que recibir\u00e1 a los destacados artistas que componen la grilla, como as\u00ed tambi\u00e9n, para poner en condiciones el predio donde transcurrir\u00e1n las tres jornadas festivaleras, en las que se espera una gran concurrencia de p\u00fablico, tal como sucede en cada edici\u00f3n. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO7.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-703 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO7.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO7.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO7.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO10.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-704 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO10.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO10.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO10.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO4.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-705 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO4.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO4.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO4.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO5.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-706 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO5.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO5.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO5.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>OJO DE AGUA La 25\u00b0 Edici\u00f3n del Festival Nacional del Artesano en Villa Ojo de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":701,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":8,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/OJO1.jpg?fit=720%2C480&ssl=1","_links":{"self":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=700"}],"version-history":[{"count":1,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/700\/revisions"}],"predecessor-version":[{"id":707,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/700\/revisions\/707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/701"}],"wp:attachment":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}