{"id":738,"date":"2020-02-26T13:58:50","date_gmt":"2020-02-26T13:58:50","guid":{"rendered":"http:\/\/elterritorialweb.com.ar\/web\/?p=738"},"modified":"2020-02-26T13:58:53","modified_gmt":"2020-02-26T13:58:53","slug":"gran-exito-del-corso-barrial-2020-en-la-ciudad-de-frias","status":"publish","type":"post","link":"https:\/\/elterritorialweb.com.ar\/web\/gran-exito-del-corso-barrial-2020-en-la-ciudad-de-frias\/","title":{"rendered":"GRAN \u00c9XITO DEL CORSO BARRIAL 2020 EN LA CIUDAD DE FR\u00cdAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">FR\u00cdAS <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el Auspicio de la Municipalidad de Fr\u00edas y la organizaci\u00f3n del \u201cMovimiento Evita\u201d se llev\u00f3 a cabo en la noche de este lunes el Corso Barrial 2020 en la Avenida Presidente de la Plaza, B\u00ba Yapey\u00fa.<br>Miles de personas que comenzaron a llegar al centro de inter\u00e9s del Corso Barrial desde la tarde disfrutaron hasta las primeras horas del martes 25 de la interesante propuesta de los organizadores.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/2.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-740 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/2.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/2.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/2.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>M\u00fasica en vivo con Rafaelito Barrionuevo, Roberto vega y la S\u00faper Banda, Sergio Peralta y Maar Sisnero y los Herederos, y Aland Landril, la presentaci\u00f3n de numerosas comparsas representando a diferentes barrios de Fr\u00edas m\u00e1s la participaci\u00f3n de la una comparsa de la Ciudad de Santiago del Estero, le dieron el brillo y esp\u00edritu carnavalesco al pen\u00faltimo d\u00eda del fin de semana largo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/3.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-741 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/3.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/3.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/3.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Con la presencia del Intendente Dr. Astor An\u00edbal Padula, funcionarios<br>y concejales, las agrupaciones carnavaleras desfilaron frente al escenario y a los miembros de un jurado que tuvo la dif\u00edcil misi\u00f3n de elegir a los m\u00e1s representativos de la noche<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/4.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-742 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/4.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/4.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/4.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Reina: Nahira Gimena Guti\u00e9rrez<br>1\u00ba Princesa: Milagros Ayl\u00e9n L\u00f3pez<br>2\u00ba Princesa: Elsa Mar\u00eda Gordillo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bailarinas:<br>1\u00ba Demaris Gimena Acevedo<br>2\u00ba Carolina Palavecino<br>3\u00aa Kiara Arias<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comparsa: Belleza Trans<br>Murga: Sentimiento Murguero<br>Reina \u201cDrag Queen\u201d: Mariana Pineda<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/5.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-743 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/5.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/5.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/5.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El destacado jurado estuvo integrado por: Licenciada Mar\u00eda Soledad Ram\u00edrez de Padula, Ex Reina de la Ciudad, Jos\u00e9 Luis \u201cColo\u201d Pivetta, Rosa Cama\u00f1o, Julieta Quevedo y Sabrina Casalet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"427\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/6.jpg?resize=640%2C427\" alt=\"\" class=\"wp-image-744 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/6.jpg?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/6.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/6.jpg?resize=675%2C450&amp;ssl=1 675w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/427;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Se destaca la impecable organizaci\u00f3n por parte de la agrupaci\u00f3n pol\u00edtica del \u201cMovimiento Evita\u201d de la invalorable colaboraci\u00f3n de la Municipalidad de Fr\u00edas con un trabajo en conjunto de todas sus \u00e1reas: Obras y Servicios P\u00fablicos, Tr\u00e1nsito, Guardia Urbana, Prensa y Difusi\u00f3n y todo el personal que tuvo a cargo las tareas de preproducci\u00f3n y producci\u00f3n del espect\u00e1culo callejero que cerr\u00f3 con un imponente marco de p\u00fablico para una nueva fiesta popular en la Ciudad.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" width=\"640\" height=\"960\" data-src=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/7.jpg?resize=640%2C960\" alt=\"\" class=\"wp-image-745 lazyload\" data-srcset=\"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/7.jpg?w=640&amp;ssl=1 640w, https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/7.jpg?resize=200%2C300&amp;ssl=1 200w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/960;\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>FR\u00cdAS Con el Auspicio de la Municipalidad de Fr\u00edas y la organizaci\u00f3n del \u201cMovimiento Evita\u201d&#8230;<\/p>\n","protected":false},"author":2,"featured_media":739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[21],"tags":[],"class_list":["post-738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales"],"aioseo_notices":[],"views":14,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elterritorialweb.com.ar\/web\/wp-content\/uploads\/2020\/02\/1.jpg?fit=720%2C480&ssl=1","_links":{"self":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/comments?post=738"}],"version-history":[{"count":1,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/738\/revisions"}],"predecessor-version":[{"id":746,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/posts\/738\/revisions\/746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media\/739"}],"wp:attachment":[{"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/media?parent=738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/categories?post=738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elterritorialweb.com.ar\/web\/wp-json\/wp\/v2\/tags?post=738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}